{"id":5265,"date":"2015-02-08T06:00:39","date_gmt":"2015-02-08T11:00:39","guid":{"rendered":"http:\/\/traun-photo.com\/dan\/?p=5265"},"modified":"2015-01-25T10:23:13","modified_gmt":"2015-01-25T15:23:13","slug":"2015-02-08-kellogg-mn-sunset","status":"publish","type":"post","link":"http:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/","title":{"rendered":"2015-02-08 Kellogg, MN Sunset"},"content":{"rendered":"<p>Kellogg, MN Sunset.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"2015-02-08 Kellogg, MN Sunset\" data-rl_caption=\"\" title=\"2015-02-08 Kellogg, MN Sunset\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"5266\" data-permalink=\"http:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/2015-02-08-kellogg-mn-sunset\/\" data-orig-file=\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608\" data-orig-size=\"1080,608\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D60&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1421000793&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"2015-02-08 Kellogg, MN Sunset\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=474%2C267\" class=\"alignnone size-medium wp-image-5266\" src=\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?resize=300%2C169\" alt=\"2015-02-08 Kellogg, MN Sunset\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?resize=300%2C169 300w, https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?resize=1024%2C576 1024w, https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?w=1080 1080w, https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?w=948 948w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Views: 261<\/p>","protected":false},"excerpt":{"rendered":"<p>Kellogg, MN Sunset. Views: 261<\/p>\n","protected":false},"author":1,"featured_media":5266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[912,1],"tags":[229,984,68,42,564,43],"class_list":["post-5265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-912","category-photography","tag-hwy-61","tag-kellogg","tag-minnesota","tag-snow","tag-sunset","tag-winter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2015-02-08 Kellogg, MN Sunset - dantraun.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2015-02-08 Kellogg, MN Sunset - dantraun.com\" \/>\n<meta property=\"og:description\" content=\"Kellogg, MN Sunset. Views: 261\" \/>\n<meta property=\"og:url\" content=\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/\" \/>\n<meta property=\"og:site_name\" content=\"dantraun.com\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-08T11:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dan Traun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@traunphoto\" \/>\n<meta name=\"twitter:site\" content=\"@traunphoto\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dan Traun\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/\"},\"author\":{\"name\":\"Dan Traun\",\"@id\":\"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940\"},\"headline\":\"2015-02-08 Kellogg, MN Sunset\",\"datePublished\":\"2015-02-08T11:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/\"},\"wordCount\":8,\"commentCount\":9,\"publisher\":{\"@id\":\"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940\"},\"image\":{\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608\",\"keywords\":[\"Hwy 61\",\"Kellogg\",\"Minnesota\",\"Snow\",\"Sunset\",\"Winter\"],\"articleSection\":[\"2015 (365)\",\"Photography\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/\",\"url\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/\",\"name\":\"2015-02-08 Kellogg, MN Sunset - dantraun.com\",\"isPartOf\":{\"@id\":\"http:\/\/traun-photo.com\/dan\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608\",\"datePublished\":\"2015-02-08T11:00:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608\",\"contentUrl\":\"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608\",\"width\":1080,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/traun-photo.com\/dan\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2015-02-08 Kellogg, MN Sunset\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/traun-photo.com\/dan\/#website\",\"url\":\"http:\/\/traun-photo.com\/dan\/\",\"name\":\"dantraun.com\",\"description\":\"DAN TRAUN - Photographer\",\"publisher\":{\"@id\":\"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/traun-photo.com\/dan\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940\",\"name\":\"Dan Traun\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g\",\"caption\":\"Dan Traun\"},\"logo\":{\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g\"},\"description\":\"I revel in every opportunity to capture nature and any other thing wild or unique. Candid photography is a passion of mine. Capturing a specific moment in time\u2026the un-posed and unplanned, immediate and unobtrusiveness of candids is a thrill unsurpassed by all other types of photography in my opinion. Nature photography and capturing the WI &amp; MN country sides is my current focus. I very much enjoy photographing old farmsteads, barns and other historic places with my lovely and talented wife Cyndie. DAN TRAUN PHOTOGRAPHY - RED WING, MN\",\"sameAs\":[\"http:\/\/dantraun.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2015-02-08 Kellogg, MN Sunset - dantraun.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/","og_locale":"en_US","og_type":"article","og_title":"2015-02-08 Kellogg, MN Sunset - dantraun.com","og_description":"Kellogg, MN Sunset. Views: 261","og_url":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/","og_site_name":"dantraun.com","article_published_time":"2015-02-08T11:00:39+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608&ssl=1","type":"image\/jpeg"}],"author":"Dan Traun","twitter_card":"summary_large_image","twitter_creator":"@traunphoto","twitter_site":"@traunphoto","twitter_misc":{"Written by":"Dan Traun"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#article","isPartOf":{"@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/"},"author":{"name":"Dan Traun","@id":"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940"},"headline":"2015-02-08 Kellogg, MN Sunset","datePublished":"2015-02-08T11:00:39+00:00","mainEntityOfPage":{"@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/"},"wordCount":8,"commentCount":9,"publisher":{"@id":"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940"},"image":{"@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608","keywords":["Hwy 61","Kellogg","Minnesota","Snow","Sunset","Winter"],"articleSection":["2015 (365)","Photography"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/","url":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/","name":"2015-02-08 Kellogg, MN Sunset - dantraun.com","isPartOf":{"@id":"http:\/\/traun-photo.com\/dan\/#website"},"primaryImageOfPage":{"@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage"},"image":{"@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608","datePublished":"2015-02-08T11:00:39+00:00","breadcrumb":{"@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#primaryimage","url":"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608","contentUrl":"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608","width":1080,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/traun-photo.com\/dan\/2015-02-08-kellogg-mn-sunset\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/traun-photo.com\/dan\/"},{"@type":"ListItem","position":2,"name":"2015-02-08 Kellogg, MN Sunset"}]},{"@type":"WebSite","@id":"http:\/\/traun-photo.com\/dan\/#website","url":"http:\/\/traun-photo.com\/dan\/","name":"dantraun.com","description":"DAN TRAUN - Photographer","publisher":{"@id":"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/traun-photo.com\/dan\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"http:\/\/traun-photo.com\/dan\/#\/schema\/person\/cb7891f856907078cfc8e04870209940","name":"Dan Traun","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g","caption":"Dan Traun"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/86eb6e640c19cd459e767335f3d7e426f227b1ef9da3cb5c7f814185e0953e86?s=96&d=identicon&r=g"},"description":"I revel in every opportunity to capture nature and any other thing wild or unique. Candid photography is a passion of mine. Capturing a specific moment in time\u2026the un-posed and unplanned, immediate and unobtrusiveness of candids is a thrill unsurpassed by all other types of photography in my opinion. Nature photography and capturing the WI &amp; MN country sides is my current focus. I very much enjoy photographing old farmsteads, barns and other historic places with my lovely and talented wife Cyndie. DAN TRAUN PHOTOGRAPHY - RED WING, MN","sameAs":["http:\/\/dantraun.com"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/traun-photo.com\/dan\/wp-content\/uploads\/2015\/01\/2015-02-08-Kellogg-MN-Sunset.jpg?fit=1080%2C608","jetpack_shortlink":"https:\/\/wp.me\/p4cNAT-1mV","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/posts\/5265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/comments?post=5265"}],"version-history":[{"count":1,"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/posts\/5265\/revisions"}],"predecessor-version":[{"id":5267,"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/posts\/5265\/revisions\/5267"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/media\/5266"}],"wp:attachment":[{"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/media?parent=5265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/categories?post=5265"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/traun-photo.com\/dan\/wp-json\/wp\/v2\/tags?post=5265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}